{"id":3919,"date":"2023-02-08T09:28:39","date_gmt":"2023-02-08T09:28:39","guid":{"rendered":"https:\/\/apefadal.es\/?p=3919"},"modified":"2024-02-14T11:44:03","modified_gmt":"2024-02-14T11:44:03","slug":"v-international-molkky-championship-playing-in-family","status":"publish","type":"post","link":"https:\/\/apefadal.es\/index.php\/2023\/02\/08\/v-international-molkky-championship-playing-in-family\/","title":{"rendered":"V International M\u00f6lkky Championship &#8211; Playing in Family"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-align-center\">V CAMPEONATO INTERNACIONAL DE M\u00d6LKKY JUGANDO EN FAMILIA POR LA IGUALDAD <\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>12 DE MARZO DE 2023 A LAS 10:30 EN GETAFE<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong><a href=\"https:\/\/apefadal.es\/index.php\/2022\/02\/08\/1-juegos-escandinavos-de-precision-y-estrategia\/\" data-type=\"URL\" data-id=\"https:\/\/apefadal.es\/index.php\/2022\/02\/08\/1-juegos-escandinavos-de-precision-y-estrategia\/\">Sesi\u00f3n incorporada en el curso de 1 cr\u00e9dito v\u00e1lido para sexenios :  \u00ab<strong>APLICACI\u00d3N DID\u00c1CTICA DE DEPORTES DE BLANCO Y DIANA<\/strong>\u00ab<\/a><\/strong>*<\/p>\n\n\n\n<p class=\"has-text-align-center\">*IMPORTANTE: Profesorado interesado en realizar el curso debe rellenar el formulario de inscripci\u00f3n del campeonato y el del curso.<\/p>\n\n\n\n<div id=\"gmdf9b24f\" class=\"wp-block-gutentor-m1 section-gmdf9b24f gutentor-module gutentor-element-button-group has-color-bg has-custom-bg button-align-center-desktop g-btn-horizontal-d g-btn-horizontal-t g-btn-horizontal-m\"><div class=\"gutentor-element-button-group-wrap\">\n<div id=\"section-g7cb1e5\" class=\"wp-block-gutentor-e2 section-g7cb1e5 gutentor-element gutentor-element-button\"><span class=\"gutentor-button-wrap\"><a class=\"gutentor-button gutentor-block-button gutentor-icon-hide\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSelCA3aon6cfH8VBqtW18VyPyYuQPSVrF-EhvhjcZ2mahcH8Q\/viewform\" target=\"_blank\" rel=\"noopener noreferrer\"><i class=\"gutentor-button-icon fas fa-book\"><\/i><span>Formulario de Inscripci\u00f3n<\/span><\/a><\/span><\/div>\n\n\n\n<div id=\"section-g3d424c\" class=\"wp-block-gutentor-e2 section-g3d424c gutentor-element gutentor-element-button\"><span class=\"gutentor-button-wrap\"><a class=\"gutentor-button gutentor-block-button gutentor-icon-hide\" href=\"https:\/\/goo.gl\/maps\/sgfCdX3myBEe3k1y6\" target=\"_blank\" rel=\"noopener noreferrer\"><i class=\"gutentor-button-icon fas fa-book\"><\/i><span>\u00bfC\u00f3mo llegar?<\/span><\/a><\/span><\/div>\n\n\n\n<div id=\"section-g9e5684\" class=\"wp-block-gutentor-e2 section-g9e5684 gutentor-element gutentor-element-button\"><span class=\"gutentor-button-wrap\"><a class=\"gutentor-button gutentor-block-button gutentor-icon-hide\" href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2023\/02\/Molkky-Normativa-International-2023.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><i class=\"gutentor-button-icon fas fa-book\"><\/i><span>Reglamento<\/span><\/a><\/span><\/div>\n\n\n\n<div id=\"section-g58a833\" class=\"wp-block-gutentor-e2 section-g58a833 gutentor-element gutentor-element-button\"><span class=\"gutentor-button-wrap\"><a class=\"gutentor-button gutentor-block-button gutentor-icon-hide\" href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-03-11-at-21.20.30-724x1024.jpeg\" target=\"_blank\" rel=\"noopener noreferrer\"><i class=\"gutentor-button-icon fas fa-book\"><\/i><span>Cuadro de competici\u00f3n<\/span><\/a><\/span><\/div>\n<\/div><\/div>\n\n\n\n<p>El evento se desarrollar\u00e1 6 de Marzo de 2022 a las 10:30 horas, en las pistas de Petanca junto al polideportivo Cerro Buenavista del Sector 3 de Getafe -Madrid -Spain (Avenida Arcas del Agua s\/n), siguiendo las medidas sanitarias vigentes para la prevenci\u00f3n de la Covid_19.<\/p>\n\n\n\n<p>NO hace falta CONOCER EL JUEGO para Participar, Disfrutar y ser Campe\u00f3n-a<\/p>\n\n\n\n<p><strong>Inscripciones<\/strong>&nbsp;<strong><a href=\"https:\/\/forms.gle\/RKrzwmNjjbQG6dNW6\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forms.gle\/RKrzwmNjjbQG6dNW6<\/a><\/strong>  o por escrito al Tfno. 619 34 70 98. Inscripciones abiertas <strong>hasta el 3 de marzo<\/strong>.<\/p>\n\n\n\n<p>Trofeos para los 3 primeros equipos<\/p>\n\n\n\n<div id=\"section-g4f26eb\" class=\"wp-block-gutentor-e6 section-g4f26eb gutentor-element gutentor-element-image text-align-center-desktop\"><div class=\"gutentor-element-image-box\"><div class=\"gutentor-image-thumb\"><img decoding=\"async\" class=\"normal-image\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2023\/02\/WhatsApp-Image-2023-03-11-at-21.20.30-724x1024.jpeg\" \/><\/div><\/div><\/div>\n\n\n\n<div id=\"section-g25d76f\" class=\"wp-block-gutentor-e6 section-g25d76f gutentor-element gutentor-element-image text-align-center-desktop\"><div class=\"gutentor-element-image-box\"><div class=\"gutentor-image-thumb\"><img decoding=\"async\" class=\"normal-image\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2023\/02\/Cto-Molkky-internacional-plano-campos-2023-red-1024x724.jpg\" \/><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\" id=\"normas-basicas-del-juego\">NORMAS B\u00c1SICAS DEL JUEGO<\/h2>\n\n\n\n<p>-El \u201cM\u00f6lkky\u201d siempre es lanzado con la mano por abajo.<\/p>\n\n\n\n<p>-Despu\u00e9s del lanzamiento si se sale hacia delante o por el lateral del M\u00f6lkkari la puntuaci\u00f3n del lanzamiento ser\u00e1 0 puntos<\/p>\n\n\n\n<p>-No se considera bolo ca\u00eddo si cae encima de otro \u00f3 sobre el M\u00f6lkky.<\/p>\n\n\n\n<p>-Si cae s\u00f3lo \u201c1 bolo\u201d, los puntos corresponden al n\u00famero del bolo ca\u00eddo.<\/p>\n\n\n\n<p>-Cuando caen m\u00e1s de un bolo, se anotan el n\u00famero de bolos ca\u00eddos.<\/p>\n\n\n\n<p>-Despu\u00e9s de cada lanzamiento, poner los bolos en el lugar exacto en donde cayeron.<\/p>\n\n\n\n<p>-Si un jugador o jugadora no acierta (no tiene puntuaci\u00f3n) si le sucede lo mismo en tres ocasiones consecutivas, queda fuera del juego. En Espa\u00f1a sigue jugando pero iniciando desde 0 puntos<\/p>\n\n\n\n<p>-El juego termina cuando el primer jugador-a alcance exactamente los 50 puntos. Si anota m\u00e1s de 50 puntos, a este jugador-a o equipo se le rebajar\u00e1 su marcador a 25 puntos.<\/p>\n\n\n\n<p>-El M\u00f6lkkout es un juego r\u00e1pido para situaciones de empate. Se necesitan cinco bolos.&nbsp;Ponerlos en una fila a una distancia de 3,5 metros de la M\u00f6lkkaari de manera que el primero es el bolo n\u00famero 6, a continuaci\u00f3n, 4, 12, 10 y 8. Entre cada bolo hay una distancia que es la misma que la longitud del bolo de lanzamiento (M\u00f6lkky) = 225 mm<\/p>\n\n\n\n<p>Cada equipo (y cada jugador dentro de un equipo) se turna para tirar el M\u00f6lkky a los bolos. Cuando un bolo ha sido derribado, se vuelve a levantar donde estaba originalmente. El sistema de puntuaci\u00f3n es el mismo que en el M\u00f6lkky. El m\u00f6lkkout contin\u00faa hasta que dos participantes de cada equipo lancen una vez. En este momento, el equipo que obtuvo m\u00e1s puntos gana el m\u00f6lkkout. Si todav\u00eda hay igualdad en el n\u00famero de puntos, el m\u00f6lkkout contin\u00faa en \u00abmuerte s\u00fabita\u00bb en cada turno.<\/p>\n\n\n\n<p>-De forma excepcional en el partido final si jugar\u00e1 el saque con el M\u00f6lkkout<\/p>\n\n\n\n<p>Un jugador de cada equipo tirara una vez, seg\u00fan la puntuaci\u00f3n inversa a la puntuaci\u00f3n un segundo jugador tirar\u00e1 otra vez, seg\u00fan el resultado de mayor puntuaci\u00f3n se realizar\u00e1 el saque (en caso de empate se sortea de cualquier forma)<\/p>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3043.215398145263!2d-3.7478191332118818!3d40.29317608968974!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd418b35f76586a5%3A0x188ca58d883331e2!2sPolideportivo%20P%C3%BAblico%20Sector%203!5e0!3m2!1ses!2ses!4v1643968779835!5m2!1ses!2ses\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe>\n\n\n\n<p><strong>Inscripci\u00f3n previa<\/strong>, Plazas limitadas. Equipos de 2 \u00f3 3 participantes<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"> <\/h2>\n","protected":false},"excerpt":{"rendered":"<p>V CAMPEONATO INTERNACIONAL DE M\u00d6LKKY JUGANDO EN FAMILIA POR LA IGUALDAD 12 DE MARZO DE 2023 A LAS 10:30 EN GETAFE Sesi\u00f3n incorporada en el curso de 1 cr\u00e9dito v\u00e1lido para sexenios : \u00abAPLICACI\u00d3N DID\u00c1CTICA DE DEPORTES DE BLANCO Y DIANA\u00ab* *IMPORTANTE: Profesorado interesado en realizar el curso debe rellenar el formulario de inscripci\u00f3n del&hellip;<\/p>\n","protected":false},"author":1,"featured_media":3923,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[494,5,6],"tags":[],"class_list":["post-3919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aemolkky","category-comunicados","category-comunicados-cursos"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/comments?post=3919"}],"version-history":[{"count":7,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3919\/revisions"}],"predecessor-version":[{"id":4977,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3919\/revisions\/4977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media\/3923"}],"wp:attachment":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media?parent=3919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/categories?post=3919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/tags?post=3919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}