{"id":3450,"date":"2022-09-09T09:56:35","date_gmt":"2022-09-09T09:56:35","guid":{"rendered":"https:\/\/apefadal.es\/?p=3450"},"modified":"2023-09-12T08:14:08","modified_gmt":"2023-09-12T08:14:08","slug":"i-campeonato-de-espana-de-cornhole-indoor","status":"publish","type":"post","link":"https:\/\/apefadal.es\/index.php\/2022\/09\/09\/i-campeonato-de-espana-de-cornhole-indoor\/","title":{"rendered":"I Campeonato de Espa\u00f1a de Cornhole indoor"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">I Campeonato de Espa\u00f1a de Cornhole indoor &#8211; Jugando en familia por la igualdad<\/h2>\n\n\n\n<p><strong>Categor\u00edas:<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\">Jugaremos en las <strong>categor\u00edas Individuales<\/strong>: (no olvides buscar una pareja para jugar por equipos, los campeonatos son compatibles)<\/p>\n\n\n\n<ul class=\"has-small-font-size wp-block-list\">\n<li>Masculina<\/li>\n\n\n\n<li>Femenina<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\"><strong>Categor\u00edas parejas:<\/strong> (compatibles entre s\u00ed)<\/p>\n\n\n\n<ul class=\"has-small-font-size wp-block-list\">\n<li>Familia<\/li>\n\n\n\n<li>Amigxs.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p class=\"has-small-font-size\"><strong>Premios y regalos:<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\">Habr\u00e1 trofeos para el p\u00f3dium de cada categor\u00eda y algunas sorpresas de nuestro colaborador:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/wickedwoodgames.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"413\" height=\"328\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2021\/04\/wickedwoodgames-e1619687739800.jpg\" alt=\"\" class=\"wp-image-2116\"\/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background has-medium-font-size\"><strong>\u00bfD\u00f3nde?<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\">En el <strong>Gimnasio del Colegio P\u00fablico Ana Mar\u00eda Matute. Avenida Rosa Chacel, 4, 28903 Getafe, Madrid<\/strong>. El <strong>S\u00e1bado 26 de noviembre de 2022 a las 9:15 horas<\/strong><\/p>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d1278.8511977990079!2d-3.725788332348293!3d40.32819344572254!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd4220ca42c220d9%3A0x3db2b6111b820fe3!2sColegio%20P%C3%BAblico%20Ana%20Mar%C3%ADa%20Matute!5e0!3m2!1ses!2ses!4v1669205254265!5m2!1ses!2ses\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background has-medium-font-size\"><strong>Programa<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">9:15 a 9:30 horas Control de participaci\u00f3n, pr\u00e9stamo de sacos.<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">9:30 Repaso de la organizaci\u00f3n y normativa<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Campeonato <strong>Individual FEMENINO<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><strong>&#8211;<\/strong>10:00 a 10:50 horas Fase clasificatoria<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-10:50 a 11:15 horas Semifinales y FINAL<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Campeonato <strong>Individual MASCULINO<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-10:30 a 10:50 Fase previa<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-11:15 a 12:05 Fase clasificatoria<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-12:05 a 12:30 Semifinales y FINAL<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\"><strong>Foto oficial<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Campeonato <strong>Equipos FAMILIA<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-11:45 a 12:05 Fase previa<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-12:30 a 13:20 Fase clasificatoria<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-13:20 a 13:45 Semifinales y FINAL<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">Campeonato <strong>Equipos ABSOLUTA<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-13:45 a 14:35 Fase clasificatoria<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-14:35 a 15 Semifinales y FINAL<\/p>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">-15 horas. <strong>Entrega de Trofeos<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background has-medium-font-size\"><strong>Cuadrantes competitivos Individuales<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-scaled.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1810\" height=\"2560\" data-id=\"3827\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-scaled.jpg\" alt=\"\" class=\"wp-image-3827\" srcset=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-scaled.jpg 1810w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-212x300.jpg 212w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-724x1024.jpg 724w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-768x1086.jpg 768w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-1086x1536.jpg 1086w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Femenino-1448x2048.jpg 1448w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-scaled.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2285\" data-id=\"3828\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-scaled.jpg\" alt=\"\" class=\"wp-image-3828\" srcset=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-scaled.jpg 2560w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-300x268.jpg 300w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-1024x914.jpg 1024w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-768x685.jpg 768w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-1536x1371.jpg 1536w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-Previo-2048x1828.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-scaled.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1810\" height=\"2560\" data-id=\"3829\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-scaled.jpg\" alt=\"\" class=\"wp-image-3829\" srcset=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-scaled.jpg 1810w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-212x300.jpg 212w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-724x1024.jpg 724w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-768x1086.jpg 768w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-1086x1536.jpg 1086w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Individual-Masculino-1448x2048.jpg 1448w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-scaled.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2285\" data-id=\"3836\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-scaled.jpg\" alt=\"\" class=\"wp-image-3836\" srcset=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-scaled.jpg 2560w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-300x268.jpg 300w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-1024x914.jpg 1024w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-768x685.jpg 768w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-1536x1371.jpg 1536w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Previo-2048x1828.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-scaled.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1810\" height=\"2560\" data-id=\"3834\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-scaled.jpg\" alt=\"\" class=\"wp-image-3834\" srcset=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-scaled.jpg 1810w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-212x300.jpg 212w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-724x1024.jpg 724w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-768x1086.jpg 768w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-1086x1536.jpg 1086w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Familia-Rellena-1448x2048.jpg 1448w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-scaled.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1810\" height=\"2560\" data-id=\"3833\" src=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-scaled.jpg\" alt=\"\" class=\"wp-image-3833\" srcset=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-scaled.jpg 1810w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-212x300.jpg 212w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-724x1024.jpg 724w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-768x1086.jpg 768w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-1086x1536.jpg 1086w, https:\/\/apefadal.es\/wp-content\/uploads\/2022\/09\/Planillas-2022-8-campos-Absoluta-Rellena-1448x2048.jpg 1448w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background has-medium-font-size\"><strong>Normativa<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li><strong>Se desarrollar\u00e1 seg\u00fan las medidas sanitarias aplicables en ese momento por la Covid_19.<\/strong><\/li>\n\n\n\n<li>Los Encuentros se realizar\u00e1n en un ambiente festivo-l\u00fadico-deportivo.<\/li>\n\n\n\n<li>Tan importante ser\u00e1 saber perder, como ganar. Todxs ganaremos de la experiencia. Durante el desarrollo de una ronda intentaremos minimizar las reacciones tras nuestros de lanzamientos.<\/li>\n\n\n\n<li>Se aconseja que cada equipo lleve la misma equipaci\u00f3n o similar.<\/li>\n\n\n\n<li>Todo el material deber\u00e1 permanecer siempre en el terreno de juego correspondiente, se ruega no cambiarlo de campo.<\/li>\n\n\n\n<li>Se aconseja que cada equipo lleve sus propios sacos, tenemos una amplia oferta con motivo del campeonato. Dejaremos un juego de sacos al equipo que no tenga al principio del campeonato que tendr\u00e1n que devolver al final de su participaci\u00f3n.<\/li>\n\n\n\n<li>Jugaremos en la modalidad \u201crel\u00e1mpago\u201d, tiempo y partida reducida, se jugar\u00e1 a un juego de 21 puntos con un m\u00e1ximo de tiempo de 10 minutos a 20 minutos seg\u00fan el calendario adjunto. El tiempo de juego es a <strong>\u201ccron\u00f3metro corrido\u201d<\/strong> sin parar el crono.<\/li>\n\n\n\n<li>Si un equipo no est\u00e1 presente en el comienzo del turno de juego se le dar\u00e1 como perdido.<\/li>\n\n\n\n<li>No estar\u00e1 permitido perder tiempo durante el desarrollo del juego.<\/li>\n\n\n\n<li>Cada partido se juega con el objetivo de llegar a un juego de 21 puntos en el tiempo otorgado a la ronda correspondiente. 3 puntos meter el saco en el agujero 1 punto dejarlo sobre el tablero. En cada ronda se punt\u00faa la diferencia de puntos entre los equipos.<\/li>\n\n\n\n<li>Cuando suene la alarma, autom\u00e1ticamente se para el juego. Si se precisa se realizar\u00e1 un lanzamiento m\u00e1s para terminar con la misma cantidad de lanzamientos entre los equipos (par). En caso de empate se ir\u00e1 realizando lanzamientos de 1 en 1 hasta conseguir el desempate.<\/li>\n\n\n\n<li>Jugaremos por sistema de doble eliminatoria. Se est\u00e1 jugando hasta que se pierden dos partidos (menos en la serie previa).<\/li>\n\n\n\n<li>En la semifinal se realizar\u00e1 un sorteo para los emparejamientos de los 4 equipos<\/li>\n\n\n\n<li>En la final y en partido por el 3\u00ba y 4\u00ba puesto, se jugar\u00e1 a un juego de 21 puntos, con un tiempo m\u00e1ximo de 15 minutos. Se tiene que terminar la ronda en individual o la entrada en equipos (todos los participantes tirar\u00e1n la misma cantidad de sacos).<\/li>\n\n\n\n<li>Habr\u00e1 dos campos de pr\u00e1cticas en el pabell\u00f3n que de forma rotativa en cada per\u00edodo de juego podr\u00e1n usarse l@s participantes del siguiente campeonato. <\/li>\n<\/ol>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size\"><strong>NORMAS DEL COMIENZO DEL JUEGO<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"1\">\n<li><strong>En individuales<\/strong>, el ganador\/a del sorteo sacar\u00e1 y decidir\u00e1 qu\u00e9 carril ocupar\u00e1 durante todo el juego.<\/li>\n\n\n\n<li><strong>En dobles<\/strong>, el ganador\/a del sorteo decidir\u00e1 que jugador (o qu\u00e9 equipo) empieza lanzando y adem\u00e1s elegir\u00e1 entre:\n<ol class=\"wp-block-list\">\n<li>Qu\u00e9 carril ocupar\u00e1 su equipo durante todo el juego, as\u00ed como la posici\u00f3n respectiva de los 2 jugadores de su equipo en la calle seleccionada<\/li>\n\n\n\n<li>El enfrentamiento de los jugadores de cada tablero (qu\u00e9 jugador de su equipo jugar\u00e1 contra qu\u00e9 jugador del otro equipo) durante todo el juego.<\/li>\n<\/ol>\n<\/li>\n\n\n\n<li><strong>En dobles<\/strong>, el perdedor\/a del sorteo decidir\u00e1 la otra opci\u00f3n.<\/li>\n\n\n\n<li><strong>En individuales o dobles<\/strong>, el ganador\/a del sorteo tambi\u00e9n elegir\u00e1 qu\u00e9 jugador\/a (o qu\u00e9 equipo) lanzar\u00e1 la primera bolsa del juego.<\/li>\n\n\n\n<li>El ganador\/a del sorteo elegir\u00e1 el color de las bolsas que \u00e9l\/ella (o su equipo) utilizar\u00e1 durante todo el juego en caso que sean iguales.<\/li>\n<\/ol>\n\n\n\n<p class=\"has-text-align-center\"><strong>Esta normativa podr\u00e1 ser modificada antes y durante el desarrollo del evento por necesidades de la organizaci\u00f3n.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-c8333759-32ce-4053-9ba8-9cf0f25c7a41\" href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/11\/Normas-del-Cpto-Indoor-2022-Daniel-1.docx\" target=\"_blank\" rel=\"noreferrer noopener\">Normas-del-Cpto-Indoor-2022<\/a><a href=\"https:\/\/apefadal.es\/wp-content\/uploads\/2022\/11\/Normas-del-Cpto-Indoor-2022-Daniel-1.docx\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-c8333759-32ce-4053-9ba8-9cf0f25c7a41\">Descargar en PDF<\/a><\/div>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background has-medium-font-size\"><strong>\u00bfC\u00f3mo me inscribo?<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\">INSCRIPCIONES CERRADAS. Rellenando el formulario de inscripci\u00f3n. Si te apuntas con un amigo y con un familiar, deber\u00e1s rellenar dos formularios para la otra categor\u00eda sin volver a apuntarte al campeonato individual que quieras.<\/p>\n\n\n\n<p class=\"has-text-align-center has-luminous-vivid-amber-background-color has-background has-medium-font-size\"><strong>INICIACI\u00d3N PREVIA AL CAMPEONATO EN COLABORACI\u00d3N CON EL AMPA DEL CEIP ANA MAR\u00cdA MATUTE<\/strong><\/p>\n\n\n\n<p>Ser\u00e1 el 25 de noviembre de 2022. a las 17:30 horas en el gimnasio del CEIP Ana Mar\u00eda Matute de Getafe&nbsp; &nbsp;&nbsp;<br>La inscripci\u00f3n es Gratuita pero limitada. La inscripci\u00f3n previa necesaria:<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a rel=\"noreferrer noopener\" href=\"https:\/\/forms.gle\/1FJPiGkoPgMLNaDZ6\" data-type=\"URL\" data-id=\"https:\/\/forms.gle\/1FJPiGkoPgMLNaDZ6\" target=\"_blank\"><strong>FORMULARIO DE INSCRIPCI\u00d3N A LA INICIACI\u00d3N. <\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I Campeonato de Espa\u00f1a de Cornhole indoor &#8211; Jugando en familia por la igualdad Categor\u00edas: Jugaremos en las categor\u00edas Individuales: (no olvides buscar una pareja para jugar por equipos, los campeonatos son compatibles) Categor\u00edas parejas: (compatibles entre s\u00ed) Premios y regalos: Habr\u00e1 trofeos para el p\u00f3dium de cada categor\u00eda y algunas sorpresas de nuestro colaborador:&hellip;<\/p>\n","protected":false},"author":1,"featured_media":3451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[577,5],"tags":[531,655,11],"class_list":["post-3450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ae-cornhole","category-comunicados","tag-cornhole","tag-getafe","tag-igualdad"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/comments?post=3450"}],"version-history":[{"count":12,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3450\/revisions"}],"predecessor-version":[{"id":4546,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3450\/revisions\/4546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media\/3451"}],"wp:attachment":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media?parent=3450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/categories?post=3450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/tags?post=3450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}