{"id":3303,"date":"2022-05-17T08:31:50","date_gmt":"2022-05-17T08:31:50","guid":{"rendered":"https:\/\/apefadal.es\/?p=3303"},"modified":"2022-05-17T08:31:53","modified_gmt":"2022-05-17T08:31:53","slug":"comunicado-interno-6-2022","status":"publish","type":"post","link":"https:\/\/apefadal.es\/index.php\/2022\/05\/17\/comunicado-interno-6-2022\/","title":{"rendered":"COMUNICADO INTERNO 6\/2022"},"content":{"rendered":"\n<p class=\"has-text-align-center has-luminous-vivid-orange-color has-text-color has-background has-medium-font-size\" style=\"background-color:#14205c\"><b>SUSPENSI\u00d3N DEL CURSO:  \u201c<\/b><strong style=\"font-weight: bold;\">ROUNDNET Y TCHOUKBALL Y SU APLICACI\u00d3N ESCOLAR<\/strong><strong><strong>\u201d<\/strong>.<\/strong><\/p>\n\n\n\n<p>Lamento comunicaros que no hemos alcanzado el m\u00ednimo de 15 inscripciones para la actividad \u00ab<strong><strong style=\"font-weight: bold;\">ROUNDNET Y TCHOUKBALL Y SU APLICACI\u00d3N ESCOLAR<\/strong><\/strong>\u00bb\u00a0 por lo que no podemos sacarlo adelante. Sospechamos que es debido a la oposici\u00f3n, aunque es el primer a\u00f1o que nos pasa de esta forma.<br><br>Durante el primer trimestre del curso que viene, os haremos llegar unos formularios para escoger qu\u00e9 actividades de las programadas para este curso os interesan y cu\u00e1ndo quer\u00e9is realizarlas el curso que\u00a0viene.<\/p>\n\n\n\n<p>Por \u00faltimo os pido que respond\u00e1is al correo que os hemos enviado, inform\u00e1ndonos si quer\u00e9is pasar vuestra inscripci\u00f3n a otro curso&nbsp;o si quer\u00e9is que os devolvamos la cuota, en cuyo caso facilitarnos vuestro n\u00famero de cuenta IBAN. ABJ tiene bastantes inscripciones ya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUSPENSI\u00d3N DEL CURSO: \u201cROUNDNET Y TCHOUKBALL Y SU APLICACI\u00d3N ESCOLAR\u201d. Lamento comunicaros que no hemos alcanzado el m\u00ednimo de 15 inscripciones para la actividad \u00abROUNDNET Y TCHOUKBALL Y SU APLICACI\u00d3N ESCOLAR\u00bb\u00a0 por lo que no podemos sacarlo adelante. Sospechamos que es debido a la oposici\u00f3n, aunque es el primer a\u00f1o que nos pasa de esta&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados-cursos"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/comments?post=3303"}],"version-history":[{"count":1,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3303\/revisions"}],"predecessor-version":[{"id":3304,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/3303\/revisions\/3304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media\/2844"}],"wp:attachment":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media?parent=3303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/categories?post=3303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/tags?post=3303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}