{"id":1826,"date":"2021-03-07T18:36:59","date_gmt":"2021-03-07T18:36:59","guid":{"rendered":"https:\/\/apefadal.es\/?p=1826"},"modified":"2023-03-31T08:07:01","modified_gmt":"2023-03-31T08:07:01","slug":"efectoigualdad-2021-mujer-montana","status":"publish","type":"post","link":"https:\/\/apefadal.es\/index.php\/2021\/03\/07\/efectoigualdad-2021-mujer-montana\/","title":{"rendered":"EFectoIGUALDAD 2021 &#8211; Mujer Monta\u00f1a"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center has-luminous-vivid-orange-color has-text-color has-background has-medium-font-size\" style=\"background-color:#14205c\"><strong>Coreograf\u00eda 8 de marzo 2021 \/\/ Mujer Monta\u00f1a &#8211; Wendy Sulca, Marie &amp; Susana Baca<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Coreograf\u00eda 8 de marzo 2021 \/\/ Mujer Monta\u00f1a - Wendy Sulca, Marie &amp; Susana Baca \/\/ #EFectoIgualdad\u200b\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/FJ_KN7TuWPs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Coreograf\u00eda 8 de marzo 2021 \/\/ Mujer Monta\u00f1a &#8211; Wendy Sulca, Marie &amp; Susana Baca \/\/&nbsp;<a href=\"https:\/\/www.youtube.com\/hashtag\/efectoigualdad\">#EFectoIgualdad\u200b<\/a><\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<p>Un a\u00f1o m\u00e1s os proponemos una coreograf\u00eda para conmemorar el 8 de marzo, D\u00eda Internacional de la Mujer. Hemos elegido la canci\u00f3n Mujer Monta\u00f1a de Wendy Sulca, Marie y Susana Baca que recoge a la perfecci\u00f3n todo lo que a\u00fan se debe reivindicar cada d\u00eda. <\/p>\n\n\n\n<p>Os animamos a que esta semana del 8M utilic\u00e9is el v\u00eddeo con vuestro alumnado, aunque no hay por qu\u00e9 esperar a estas fechas para hablar de un tema tan importante y en conclusi\u00f3n, hacer que nuestras clases de Educaci\u00f3n F\u00edsica sean espacios libres de estereotipos, desigualdades y que abracen la diversidad. Nos encantar\u00e1 ver vuestros v\u00eddeos y fotograf\u00edas, hac\u00e9rnoslas llegar a nuestro mail o compartidla en redes sociales utilizando el hastag <a href=\"https:\/\/www.youtube.com\/hashtag\/efectoigualdad\">#EFectoIgualdad<\/a>\u200b <\/p>\n\n\n\n<p>Coreograf\u00eda y baile: Ant\u00eda Lousada y Mario Marcol <\/p>\n\n\n\n<p>Agradecimientos a escuela Backstage Rivas-Vaciamadrid<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coreograf\u00eda 8 de marzo 2021 \/\/ Mujer Monta\u00f1a &#8211; Wendy Sulca, Marie &amp; Susana Baca Un a\u00f1o m\u00e1s os proponemos una coreograf\u00eda para conmemorar el 8 de marzo, D\u00eda Internacional de la Mujer. Hemos elegido la canci\u00f3n Mujer Monta\u00f1a de Wendy Sulca, Marie y Susana Baca que recoge a la perfecci\u00f3n todo lo que a\u00fan&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1827,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,18,467],"tags":[],"class_list":["post-1826","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicados","category-coreografias","category-recursos-online"],"gutentor_comment":0,"_links":{"self":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/1826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/comments?post=1826"}],"version-history":[{"count":2,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/1826\/revisions"}],"predecessor-version":[{"id":4185,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/posts\/1826\/revisions\/4185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media\/1827"}],"wp:attachment":[{"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/media?parent=1826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/categories?post=1826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apefadal.es\/index.php\/wp-json\/wp\/v2\/tags?post=1826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}